{"id":274,"count":1,"description":"","link":"http:\/\/www.planete-flop.fr\/blog\/tag\/compatibility\/","name":"compatibility","slug":"compatibility","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.planete-flop.fr\/blog\/wp-json\/wp\/v2\/tags\/274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.planete-flop.fr\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.planete-flop.fr\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.planete-flop.fr\/blog\/wp-json\/wp\/v2\/posts?tags=274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}